{"id":6748,"date":"2018-12-02T17:59:14","date_gmt":"2018-12-02T16:59:14","guid":{"rendered":"https:\/\/osalde.org\/?p=6748"},"modified":"2021-07-31T12:23:23","modified_gmt":"2021-07-31T11:23:23","slug":"osalde-cooperacion-informe-beleko-mali-noviembre-2018","status":"publish","type":"post","link":"https:\/\/osalde.org\/eu\/osalde-cooperacion-informe-beleko-mali-noviembre-2018\/","title":{"rendered":"Osalde cooperaci\u00f3n: Informe Beleko-Mal\u00ed Noviembre 2018"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text]Maite L\u00f3pez, Beleko noviembre 2018<\/p>\n<p><!--more--><\/p>\n<p>El pasado mes de Noviembre, tres compa\u00f1eros de Osalde, Maite L\u00f3pez enfermera y responsable del proyecto, Esther Cabriada, enfermera y Roberto Fern\u00e1ndez. de Pinedo, pediatra, se han desplazado a Mali para ultimar detalles e iniciar el desarrollo del Proyecto de Cooperaci\u00f3n \u201cFortalecimiento de las estrategias de atenci\u00f3n a la salud de las mujeres y la poblaci\u00f3n infantil, priorizando los programas de malnutrici\u00f3n y la construcci\u00f3n de resiliencia en siete Villages de Djedougou. MAL\u00cd.\u201d, financiado parcialmente por el Ayuntamiento de Bilbao y a desarrollar en los pr\u00f3ximos 12 meses.<\/p>\n<blockquote>\n<p>El objetivo del proyecto es mejorar las condiciones nutricionales de menores de cinco a\u00f1os y mujeres embarazadas en el \u00e1rea de salud de Beleko \u2013 Djedougou y, en base a ello, en este tiempo:<\/p>\n<\/blockquote>\n<ol>\n<li>Se han realizado reuniones para la presentaci\u00f3n del proyecto a todos los niveles, con personal del CSCOM, con el Dr. Bamba a la cabeza, con la ASACO, con <strong><a href=\"https:\/\/osalde.org\/projects\/cooperativa-deme-so-en-beleko-mali\/\">Deme so<\/a><\/strong>, con la Alcald\u00eda, en el dispensario de las Religiosas de Mar\u00eda Inmaculada y en cada una de las siete villages incluidas en el proyecto, con los chef de villages y una gran asisitencia popular. La aceptaci\u00f3n y el visto bueno para desarrollar el proyecto en esos diferentes \u00e1mbitos fue un\u00e1nime\u00a0 y mostr\u00e1ndose en todo momento como elementos facilitadores para el \u00e9xito del mismo.<\/li>\n<li>Posteriormente se planificaron unos talleres de formaci\u00f3n para fortalecer las capacidades de los ASC (Agentes de Salud Comunitaria) y de los Relais Comunitarios (ReCo) de las diferentes comunidades implicadas. La formaci\u00f3n fue dirigida por Katu, enfermera y responsable en terreno del proyecto y por Konat\u00e9, enfermero de primer nivel que la va a acompa\u00f1ar en ese prop\u00f3sito y en el que colabor\u00f3 el personal de Osalde desplazado. Se trabaj\u00f3 en la actualizaci\u00f3n de las pr\u00e1cticas claves como el despistaje con la tira de Shakir, su registro, los sistemas de seguimiento y\/o derivaci\u00f3n seg\u00fan correspondiera y de las formas de suplementaci\u00f3n nutricional y medicamentosa planteadas en el proyecto, tanto para los casos detectados como en la poblaci\u00f3n general. La participaci\u00f3n fue activa y entusiasta y la valoraci\u00f3n positiva de los talleres fue general.<\/li>\n<li>Una vez finalizados los talleres de formaci\u00f3n, se planificaron jornadas de despistaje en cada village, para detecci\u00f3n de ni\u00f1os con MAM (Malnutrici\u00f3n Aguda Moderada), que son los que van a ser seguidos a nivel local por ACS y ReCo y ni\u00f1os con MAS (Malnutrici\u00f3n Aguda Severa) que ser\u00e1n derivados al CSCOM de Beleko.<\/li>\n<\/ol>\n<blockquote>\n<p>La asistencia a esta jornada de despistaje en la villages se puede calificar de exitosa, ya que la captaci\u00f3n global (bien es verdad que en base a unos n\u00fameros, que nunca se sabe si son verdad) fue de 77,1% y solo con un d\u00eda despistaje. De un total de 2.455 (presuntos) ni\u00f1os de 6 meses a 59 meses, acudieron 1.894.<\/p>\n<\/blockquote>\n<p>Se adjunta cuadro por village, donde se observa que los ni\u00f1os detectados con MAM rondan, hasta ahora, el 8% y los ni\u00f1os con MAS el 1%. Estos n\u00fameros\u00a0 l\u00f3gicamente se ir\u00e1n modificando con los nuevos despistajes que se vayan haciendo, pero permiten desde ya iniciar con los ni\u00f1os MAM con la suplementaci\u00f3n nutricional y medicamentosa e ir valorando el funcionamiento de todo el cortejo log\u00edstico que se necesita, que no es peque\u00f1o en este proyecto, y testar las bondades o las fallas del mismo.<\/p>\n<p>Y es que aunque el entorno vital en que se desenvuelve todo no es precisamente facilitador creemos que con el entusiasmo de Katu, Konat\u00e9, los ACS y los ReCo seguro que se va a conseguir. Iremos viendo.<\/p>\n<p>PD: Como posdata resaltar que Esther Cabriada, el \u00faltimo d\u00eda justo antes de volver, enferm\u00f3 de malaria, que aunque inicialmente se mostr\u00f3 como potencialmente grave, ha evolucionado bien y a d\u00eda de hoy Esther est\u00e1 casi recuperada. Nos alegramos por Esther y que no decaiga.<\/p>\n<p><a href=\"https:\/\/osalde.org\/wp-content\/uploads\/2018\/12\/DESPISTAJE-VILLAGES-BELEKO.docx\">DESPISTAJE VILLAGES BELEKO<\/a><\/p>\n<p><a href=\"https:\/\/osalde.org\/wp-content\/uploads\/2018\/12\/Cuadro-Beleko-Villages.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6751\" src=\"https:\/\/osalde.org\/wp-content\/uploads\/2018\/12\/Cuadro-Beleko-Villages.png\" alt=\"\" width=\"867\" height=\"547\" srcset=\"https:\/\/osalde.org\/wp-content\/uploads\/2018\/12\/Cuadro-Beleko-Villages.png 867w, https:\/\/osalde.org\/wp-content\/uploads\/2018\/12\/Cuadro-Beleko-Villages-600x379.png 600w, https:\/\/osalde.org\/wp-content\/uploads\/2018\/12\/Cuadro-Beleko-Villages-300x189.png 300w, https:\/\/osalde.org\/wp-content\/uploads\/2018\/12\/Cuadro-Beleko-Villages-768x485.png 768w\" sizes=\"auto, (max-width: 867px) 100vw, 867px\" \/><\/a><\/p>\n<h3><a href=\"\/?p=6779\">Galer\u00eda de im\u00e1genes<\/a><\/h3>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<strong>Fuente:\u00a0<\/strong>Charla de Juan Luis Ur\u00eda en El Salvador &#8220;El Derecho Humano a la Salud&#8221;<\/p>\n<p><!--more--><\/p>\n<p><strong>EL DERECHO HUMANO A LA SALUD<\/strong><\/p>\n<blockquote>\n<p>\u201cLa enfermedad es un producto de la vida social\u201d. R. Virchow<\/p>\n<\/blockquote>\n<p>Es dif\u00edcil proponerles temas para la reflexi\u00f3n distintos a los que ya Mario Rovere les comunico a muchos de ustedes el pasado a\u00f1o en\u00a0 Cuenca (Ecuador) sobre el derecho a la salud en la Aldea Global.<\/p>\n<p>Es realmente complicado innovar a algunos de nuestros maestros, a algunos de los \u201cSalubristas\u201d que nuestra Am\u00e9rica ha producido desde los a\u00f1os 60. Pensadores como Gustavo Molina, Hern\u00e1n San Mart\u00edn, Hugo Behm, Mario Testa, \u2026.<\/p>\n<p>No es f\u00e1cil comunicar cosas muy distintas de las que escribieron los lideres de la medicina social, escritores, investigadores, profesionales de la salud, militantes, \u00a0que desde el SXIX lucharon por demostrar el profundo enraizamiento de la salud de los pueblos en las ciencias sociales, mejor dicho, de la salud como condici\u00f3n y resultado de los distintos contextos sociales, econ\u00f3micos y pol\u00edticos.<\/p>\n<p>Fueron H. Sigerist, R. Virchow, F. Engels,\u2026 los que fueron sembrando en tierras fruct\u00edferas sus ideas, al calor de las luchas obreras del primer capitalismo industrial.<\/p>\n<p>Siguieron G. Rosen, M. Terris, Knox,\u2026 y lleg\u00f3 la Comisi\u00f3n de Determinantes Sociales en mayo del 2007 en la 57\u00aa Asamblea Mundial de la Salud. Se invit\u00f3 a M Marmot, G Belinguer, Amartya Sen,\u2026entre otros, y en agosto del 2008 se present\u00f3 el primer informe con tres prioridades, con tres urgencias:<\/p>\n<ol>\n<li>Mejorar las condiciones de vida.<\/li>\n<li>Luchar contra la distribuci\u00f3n desigual del poder y los recursos.<\/li>\n<li>Medir la magnitud del problema, analizar y evaluar los efectos de las intervenciones.<\/li>\n<\/ol>\n<p>Algunos enseguida se preguntaron \u00bfY que opina la sociedad civil? \u00bfHa sido consultada? Otros y otras comentaban que no dec\u00eda nada de la guerra y de la violencia mas o menos estructural como determinante social, algunos, mas atrevidos, discut\u00edan que no pone en cuesti\u00f3n el modelo de desarrollo y no menciona apenas nada del mercado, nada del\u00a0 capitalismo neoliberal, no habla de \u2026<\/p>\n<p>La verdad es que nunca antes que hoy, la salud y el derecho humano al disfrute de la\u00a0 salud y a las cotas mas altas posibles de bienestar social, han sido tan cuestionados.<\/p>\n<p>La hegemon\u00eda del neoliberalismo en el escenario internacional en un hecho.<\/p>\n<p>La crisis, como dice Harvey, es un proceso racionalizador de la irracionalidad del capitalismo. Ni m\u00e1s ni menos. Se trata de recuperar los modelos m\u00e1s especulativos de acumulaci\u00f3n de capital. Las crisis son parte intr\u00ednseca del Sistema.<\/p>\n<p>La cultura de los derechos pol\u00edticos y sociales est\u00e1 en retroceso. El mercado manda.<\/p>\n<p>No hay arbitraje internacional. La OMS tambi\u00e9n est\u00e1 esponsorizada, precisamente para evitar la quiebra econ\u00f3mica de algunos de sus programas y servicios. No le andan a la zaga otras agencias internacionales del sistema de NNUU.<\/p>\n<p>Las transnacionales y sus representantes, siempre acompa\u00f1adas por el FMI, el BM y la OMC, intentan liderar las econom\u00edas, los gobiernos y los pueblos.<\/p>\n<p>Pero si hablamos de hegemon\u00edas y de liderazgos, hay que convenir con A. Gramsci, el gran pensador italiano que, \u00e9stas, no se tejen siempre de igual manera. Que hay que repensar los sistemas de alianzas y que organizar nuevas hegemon\u00edas es posible, tal y como Am\u00e9rica latina est\u00e1 ense\u00f1ando al mundo. Alianzas sustentadas en los intereses de las mayor\u00edas sociales. Alianzas sur-sur (en los \u00faltimos 30 a\u00f1os el comercio internacional entre los pa\u00edses del sur pas\u00f3 del 8% al 27%), alianzas que combinen lo institucional con las redes sociales, alianzas, en fin, incluyendo formas de doble poder, de nuevo tipo que hay que repensar despacio.<\/p>\n<p>Son tiempos de b\u00fasqueda y de resistencia, pero no siempre ha sido as\u00ed, y \u00a0Am\u00e9rica ha sido ejemplo de m\u00faltiples y variados caminos de conquista de derechos sociales y pol\u00edticos a lo largo de su rica historia.<\/p>\n<p>Es una lucha dif\u00edcil pero apasionante por m\u00e1s libertad y democracia, por m\u00e1s paz y menos violencia, por m\u00e1s desarrollo humano, por m\u00e1s cohesi\u00f3n social y de una vida m\u00e1s saludable para nuestras familias, para nuestras comunidades, para nuestros pueblos.<\/p>\n<p><strong>Pero vayamos por partes.<\/strong><\/p>\n<p>El derecho humano a la salud tiene que ver con los servicios de salud, con m\u00e9dicos, con acceso a los medicamentos necesarios y con capacidades tecnol\u00f3gicas diagnosticas y terap\u00e9uticas. Tienen que ver con la interculturalidad y la inclusi\u00f3n, con una nueva \u00e9tica en las relaciones medico\/paciente, con la profundidad de las Reformas emprendida en el sector, tanto en el primer nivel como en el \u00e1mbito hospitalario de la atenci\u00f3n, con las estrategias de promoci\u00f3n de la salud en el \u00e1mbito de la salud comunitaria, aunque no solo. Con la extensi\u00f3n de las coberturas de servicios y programas, con las pol\u00edticas contra la fragmentaci\u00f3n de los servicios de salud, con participaci\u00f3n popular y con la calidad en la gesti\u00f3n de los servicios, la calidad no se programa al margen de los planes de gesti\u00f3n sino que forman parte del sistema de gesti\u00f3n de las organizaciones (Oscar dixit) y en la adecuada gesti\u00f3n de los recursos humanos.<\/p>\n<p>Todo ello, a lo que volveremos mas tarde, \u00a0sin duda tiene que ver con el derecho a la salud, pero empecemos por lo importante.<\/p>\n<p>Como dec\u00eda la declaraci\u00f3n del Movimiento de Salud por los Pueblos (MSP) de octubre de este mismo a\u00f1o reunidos en Cuenca (Ecuador) \u201cnuestra lucha por el derecho a la salud se da en el centro de la crisis de la civilizaci\u00f3n capitalista\u201d.<\/p>\n<p><strong>En nuestra opini\u00f3n, hoy lo importante es<\/strong><\/p>\n<p>La pobreza y al extrema pobreza, o como vivir una vida plena de capacidades y de opciones sin inequidades.<\/p>\n<p>Una vida en la paz, sin guerras y sin violencias<\/p>\n<p>Y un ecosistema sostenible.\u00a0 Un medio ambiente fuente de vida agradable para vivir y no sujeto a agresiones y cat\u00e1strofes que sesgan vidas y quiebran sue\u00f1os y proyectos.<\/p>\n<p>Insistimos que la guerra, la pobreza y el medio en el que vivimos son el gran determinante social de nuestra salud, de nuestro bienestar. Unas breves reflexiones.<\/p>\n<h3><strong>La pobreza<\/strong><\/h3>\n<p>No nos referimos solamente a la ausencia de recursos y de medios de vida, de condiciones b\u00e1sicas de desarrollo ni a crecimientos econ\u00f3micos desarrollistas. Queremos proponer con A. Son la idea de la erradicaci\u00f3n de la extrema pobreza y de la pobreza y proponer un desarrollo humano de las capacidades de las personas, en ambientes de libertad, desarrollo de capacidades e, insistimos, de capacidades con opciones.<\/p>\n<p>Por ello en ocasiones necesitamos sostenibilidad estructural en los repartos de la riqueza y de los recursos. Por ello, en ocasiones, las formas de redistribuci\u00f3n de prestaciones social en forma de extensi\u00f3n de programas y servicios de salud, en forma de escolarizar el 100% de los ni\u00f1os y ni\u00f1as en primaria y en secundaria, y las propuesta de programas de protecci\u00f3n social de nuestra gente mayor y los mas necesitados de la sociedad, son elementos mas importantes que el crecimiento de recursos, que la acumulaci\u00f3n de recursos.<\/p>\n<p>No es hoy entendible que un crecimiento econ\u00f3mico en el desorden social y sin controles democr\u00e1ticos en su reparto sea lo necesario o lo \u00fatil. La erradicaci\u00f3n de la pobreza, y del analfabetismo, debe necesariamente ir acompa\u00f1ada con procesos de empoderamiento civil. Es en la democracia plena donde se dan las condiciones del gozar de m\u00e1s salud, de m\u00e1s libertad, de potenciar las capacidades de las personas.<\/p>\n<p>El crecimiento econ\u00f3mico, en s\u00ed mismo, ha demostrado su fracaso en claves de desarrollo humano, y las pol\u00edticas de ajuste estructural, la gravedad y la injusticia de las pol\u00edticas econ\u00f3micas que no tienen a los hombres y a las mujeres en el centro de su acci\u00f3n pol\u00edtica y social. Como dice el\u00a0 Presidente M\u00fajica, no hay crecimiento sin las personas, si no para qu\u00e9 o para quien es el crecimiento. Y debemos a\u00f1adir, no hay salud sin pol\u00edticas productivas distributivas, sostenibles, humildes, que tengan la redistribuci\u00f3n social como eje d e las pol\u00edticas.<\/p>\n<p>El PNUD afirma, sin embargo, en su \u00faltimo informe 2013 sobre el \u00cdndice de Desarrollo Humano (IDH) que por primera vez en 150 a\u00f1os la producci\u00f3n combinada de las tres econom\u00edas lideres del mundo en desarrollo, China, India y Brasil, es pr\u00e1cticamente igual al PIB combinado de las potencias industriales mas consolidadas del norte, Canad\u00e1, Francia, Alemania, Italia, el Reino Unido y Estados Unidos. Esta situaci\u00f3n significa un reequilibrio impresionante del poder econ\u00f3mico mundial. En 1950, los tres pa\u00edses juntos representaban solo el 10% de la econom\u00eda mundial.<\/p>\n<p>Al parecer la clase media del SUR crece r\u00e1pidamente en tama\u00f1o, ingresos y expectativas.<\/p>\n<p>El \u00faltimo informe de la CEPAL sostiene que el 40% de la poblaci\u00f3n con ingresos m\u00e1s bajos capta en promedio el 15% total del ingreso mientras que el 10% de la poblaci\u00f3n con \u00a0ingresos mas altos posee el 32%. Am\u00e9rica latina por tanto contin\u00faa siendo la Regi\u00f3n m\u00e1s desigual del mundo. Si bien observando los resultados de los \u00faltimos diez a\u00f1os se constatan mejoras distributivas en la mayor\u00eda de los pa\u00edses de la regi\u00f3n, la situaci\u00f3n continua siendo cr\u00edtica. De 17 pa\u00edses considerados por la CEPAL, el \u00edndice de GINI se redujo un 1% anual en nueve casos, entre ellos se encuentra Argentina, Venezuela y Bolivia., los tres con tasas superiores de reducci\u00f3n del 2%.<\/p>\n<p>La desigualdad tiene efectos perversos sobre la salud, pero tambi\u00e9n sobre la democracia y la libertad. El crecimiento general del IDH detectado en el 2013 de muchos pa\u00edses en desarrollo va acompa\u00f1ado, sin embargo, de una creciente desigualdad en los ingresos, patrones insostenibles de consumo, elevado gasto en defensa y escasa cohesi\u00f3n social.<\/p>\n<p>Si bien que la econom\u00eda crezca es una condici\u00f3n necesaria, no implica por si misma la eliminaci\u00f3n de la pobreza. Algunos programas de trasferencias condicionadas con los sectores mas desfavorecidos en Brasil, en Argentina, en Ecuador, y en M\u00e9xico, al parecer, junto con Bolivia y Venezuela,\u00a0 han contribuido en disminuir las desigualdades. Otra forma de econom\u00eda social es posible. El buen Vivir Com\u00fan, es posible.<\/p>\n<h3><strong>La guerra.<\/strong><\/h3>\n<p>Son m\u00e1s d e 30 conflictos de baja, alta o media intensidad, los que en este momento se est\u00e1n desarrollando en nuestro planeta. Solamente la silenciosa guerra en la Republica Democr\u00e1tica del Congo, en los \u00faltimos 6 a\u00f1os, arroja la cifra de m\u00e1s de 5 millones de muertos. \u00bfEn que tasa metemos estos muertos? \u00bfY los desplazados? \u00bfY las violaciones sistem\u00e1ticas de miles de mujeres? \u00bfY los ni\u00f1os soldados? Y \u00bflas epidemias en comunidades desestructuradas?<\/p>\n<p>Parece que las denominadas nuevas democracias \u00e1rabes no se estabilizan. Es dif\u00edcil que as\u00ed sea por el momento. T\u00fanez, Egipto, Libia, Mal\u00ed Y la RASD (la verg\u00fcenza de la descolonizaci\u00f3n espa\u00f1ola en el \u00e1rea) siguen siendo fuentes de conflicto, en claves de violencia. Siria, Irak, Afganist\u00e1n, Palestina, Somalia, Chechenia, Sri Lanka, \u2026<\/p>\n<p>Debemos ser optimistas, el proceso d e negociaci\u00f3n de las FARC\u00a0 con el gobierno Colombiano en La Habana y la distensi\u00f3n nuclear entre Ir\u00e1n y EEUU no son malas noticias. Esperaremos.<\/p>\n<p>Es la cultura de la violencia. Es la fascinaci\u00f3n de los polic\u00edas y los ladrones, la fascinaci\u00f3n testoter\u00f3nica por los ej\u00e9rcitos,<\/p>\n<p>Es la violencia de las desigualdades y de las hegemon\u00edas del complejo militar industrial de EEUU. Y del narcotr\u00e1fico galopante de nuestros pueblos y ciudades. La fascinaci\u00f3n del dinero contra la vida.<\/p>\n<p>Sin duda nos conviene a todos y a todas trabajar con m\u00e1s profusi\u00f3n una cultura de la paz, una cultura alternativa que se haga un hueco en los medios de comunicaci\u00f3n y abogue por otro tipo de relaciones sociales. Otras relaciones de poder.<\/p>\n<h3><strong>Nuestra casa, el cambio clim\u00e1tico.<\/strong><\/h3>\n<p>Es el calentamiento global. \u00bfD\u00f3nde metemos los 10 mil muertos del reciente hurac\u00e1n que asol\u00f3 Filipinas hace apenas unas semanas? Y antes Jap\u00f3n, y Hait\u00ed, y el hurac\u00e1n Mitch, Y el siguiente, y el katrina, en Nueva Orle\u00e1ns. Que est\u00e1 pasando? \u00bfNo vivimos en lugares seguros?<\/p>\n<p>En Nueva York, el 9 de mayo de 1992 se adopt\u00f3 la Convenci\u00f3n marco de las Naciones Unidas sobre el cambio clim\u00e1tico en la que se reconoce que el problema del cambio clim\u00e1tico es real. Parece necesario disminuir la emisi\u00f3n de gases que producen el efecto invernadero (GEI). Ya son 195 naciones las que han ratificado dicha Convenci\u00f3n.<\/p>\n<p>El 11 de diciembre del 1997 se celebra el Protocolo de Kyoto, en Jap\u00f3n, que pone en pr\u00e1ctica los tratados de la Convenci\u00f3n y exige a los 37 pa\u00edses industriales que se reunieron a estabilizar las emisiones de gases de efecto invernadero, por la quema de f\u00f3siles combustibles.<\/p>\n<p>La economista argentina Graciela Chichilnisky propuso una de las tres propuestas que se incluyeron en dicho Protocolo, los \u201cbonos\u00a0 de carbono\u201d, que son un mecanismo internacional de descontaminaci\u00f3n para reducir las emisiones contaminantes al medio ambiente.<\/p>\n<p>Parecer\u00eda urgente organizar nuevos consensos en torno a la reducci\u00f3n de emisiones causantes del calentamiento global, tanto de empresas, como en la producci\u00f3n agr\u00edcola, actividad industrial, energ\u00eda, uso de recursos naturales, entre otras.<\/p>\n<p>La alteraci\u00f3n de los equilibrios de los ecosistemas, locales o regionales est\u00e1n generando enfermedad, muerte, resistencia bacteriana, intoxicaciones, cat\u00e1strofes y exclusiones e inequidades sociales y sanitarias. La agresibidad de las trasnacionales en la deforestaci\u00f3n, y eliminaci\u00f3n de espacios naturales movidos por la mercantilizaci\u00f3n especulativa de los negocios de siempre (extractivos, gasisticos, madereros,\u2026) no para, pero las actividades de los grupos sociales, grupos ind\u00edgenas, grupos a los que se les altera el habitat inmediato y diario, van logrando \u00e9xitos, como en Ecuador, poco a poco.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Construir una salud con dignidad para las personas y para la Madre Tierra.<\/strong><\/p>\n<p>No quiero hablar de los servicios de salud y de los recursos para la salud y su influencia en garantizar el derecho humano a la salud sin hacer una menci\u00f3n especial a la violencia de g\u00e9nero, verdadera epidemia social en nuestros pa\u00edses.<\/p>\n<p>Creemos que las agresiones a las mujeres dentro y fuera del entorno familiar, las violaciones en condiciones de guerra, masivas, y de paz, las desigualdades en salud por motivos de genero, la garant\u00eda de los derechos sexuales y reproductivos, el derecho al aborto, y, en fin el respeto a la libre determinaci\u00f3n de la mujer, sobre su cuerpo y sus decisiones es a\u00fan una asignatura pendiente en nuestros pa\u00edses y debe figurar, en nuestro criterio, en la primera pagina de nuestras agendas.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Dignificar nuestras propuestas.<\/strong><\/p>\n<p>El tr\u00e1fico de mujeres con fines de explotaci\u00f3n econ\u00f3mica y sexual, la discriminaci\u00f3n de homosexuales y lesbianas, los derechos de las trabajadoras sexuales y de las personas transexuales, son problemas en los que tenemos que pensar como salubristas.<\/p>\n<p>Como profesionales de la salud como investigadores y lideres pol\u00edticos y sociales, hemos de pensar sobre del \u201cestado de la cuesti\u00f3n\u201d.<\/p>\n<p>Hablar de tasas escandalosas de embarazos adolescentes, la mayor\u00eda de ellos resultados de violaciones a ni\u00f1as y a adolescentes en el entorno familiar. De ITS o de la propagaci\u00f3n del VIH por violaciones sistematizadas, es reducir el problema a magnitudes, a n\u00fameros, siempre necesarios por otra parte, \u00a0que no pueden expresar el dolor, la verg\u00fcenza y la indignidad para la condici\u00f3n humana que supone este problema.<\/p>\n<p>Es especialmente grave el crecimiento del feminicidio, del asesinato de mujeres en\u00a0 Am\u00e9rica latina.<\/p>\n<p>Este conjunto de problemas de salud, de salud f\u00edsica y mental, no tiene otro origen que el sistema de dominaci\u00f3n de los hombres, de distribuci\u00f3n del poder en el seno de las familias, en el seno de nuestras Comunidades.<\/p>\n<p>Los distintos poderes y los medios de comunicaci\u00f3n ninguneando hasta el infinito el papel de la mujer son, en no poca medida, responsables de trasmitir culturas de opresi\u00f3n y\u00a0 falta de respeto hacia las mujeres en general.<\/p>\n<p>Atendamos las propuestas de las organizaciones feministas, de las l\u00edderes comunitarias, de las profesionales de la salud con conciencia y, en fin de nuestro propio coraz\u00f3n. Son nuestras compa\u00f1eras, hijas, madres y hermanas. Son ciudadanas, sin m\u00e1s.<\/p>\n<p>Dicho lo dicho, vayamos, a dar unas pinceladas acerca de los Servicios de Salud. Sobre los m\u00e9dicos, sobre los medicamentos sobre la Tecnolog\u00eda y sobre como lo estamos haciendo para garantizar el derecho humano a la salud.<\/p>\n<p>Desde la l\u00facida Declaraci\u00f3n del Alma Ata, en el 78, sobre la Atenci\u00f3n Primaria de la Salud y la primera Declaraci\u00f3n para la salud de los pueblos del 2000 en Bangladesh, tenemos claro la propuesta:<\/p>\n<p>Un Servicio Nacional de salud, cuya propiedad y financiamiento sea publico, la organizaci\u00f3n sea de car\u00e1cter integrado y coordinado en todos sus niveles de atenci\u00f3n, tanto en el \u00e1mbito ambulatorio como en el hospitalario; integrado y coordinado con estrategias de promoci\u00f3n y prevenci\u00f3n de la salud y con el \u00e1mbito socio sanitario, atravesado por la calidad en sus prestaciones, con criterios de equidad, esto es evitando desigualdades en sus actividades, programas y servicios, desigualdades de renta, de genero, geogr\u00e1ficas, de edad u otras condiciones f\u00edsicas o ps\u00edquicas, de condici\u00f3n \u00e9tnica o ind\u00edgena, de creencia o de grupo o clase social.<\/p>\n<p>Cuidado con las privatizaciones, algunos pensaron ya desde finales de los 80 que la salud era una gran negocio que no pod\u00edan perder. Debemos blindar los sistemas p\u00fablicos de salud en nuestros pa\u00edses y adaptarlos a lo necesario, siempre buscando las alianzas sociales oportunas para su sostenimiento y defensa.<\/p>\n<p>Un Servicio Nacional de Salud descentralizado, alejado de la fascinaci\u00f3n de la tecnolog\u00eda medica, pero utiliz\u00e1ndola en lo necesario. Con criterios de racionalizacion, producci\u00f3n, solidaridad y necesidad.<\/p>\n<p>Con accesibilidad universal a todos los servicios y a una cartera de actividades consensuada con los agentes sociales, de marcado car\u00e1cter comunitario, donde la participaci\u00f3n social sea un a verdadera escuela de empoderamiento civil en los procesos de gesti\u00f3n de los programas y servicios y tambi\u00e9n en el mismo proceso de vivencia de la enfermedad. Una participaci\u00f3n no instrumentalizada fuera de las relaciones de poder que otorga el conocimiento medico a los profesionales. Una participaci\u00f3n que busque la autogesti\u00f3n y la autonom\u00eda del paciente. Que busque la no dependencia de las personas hacia los sistemas m\u00e9dicos de atenci\u00f3n.<\/p>\n<p>El tama\u00f1o de los Servicios de Salud, la dimensi\u00f3n de las denominadas carteras de servicios o conjunto de actividades que el sistema ofrece a su poblaci\u00f3n, siempre condicionada por \u00a0las necesidades conocidas, siempre tiene que ver con la voluntad pol\u00edtica de los lideres, con las prioridades establecidas que es, al fin y al cabo, \u00a0una forma de voluntad pol\u00edtica y, \u00e9sta, con la permanente negociaci\u00f3n con los agentes sociales y comunitarios, en el marco econ\u00f3mico en el que se d\u00e9 dicha negociaci\u00f3n. Estos son los limites<\/p>\n<p>Un Servicio Nacional de Salud no fragmentado que\u00a0 produzca, que proponga sinergias en el conjunto de modelos de atenci\u00f3n a la salud de las personas y los distintos grupos sociales, gremiales o de clase.<\/p>\n<p>Un Servicio Nacional de Salud donde la pol\u00edtica de medicamentos y su acceso se enfrente con inteligencia a los mercaderes de la salud, que proponga una acceso universal a los medicamentos necesarios, seg\u00fan necesidades, que huya de culturas de consumo unidas al sector privado, y que busque sistemas de f\u00e1rmaco vigilancia y de evaluaci\u00f3n de los medicamentos, democr\u00e1ticos y cient\u00edficos.<\/p>\n<p>Un Sistema Nacional de Salud, en fin, que sea el orgullo del pa\u00eds y de su poblaci\u00f3n y que se base en la solidaridad de los j\u00f3venes con los viejos, de los sanos con los enfermos y de los ricos con los pobres. Un SNS para todos y para todas. Basado en sus decisiones en el m\u00e9todo epidemiol\u00f3gico, en la mejor evidencia cient\u00edfica, en los significados culturales de la poblaci\u00f3n y en sistemas de informaci\u00f3n unificados y desagregados. Para los pobres, para las clases medias y, tambi\u00e9n para los ricos. Que impulse el desarrollo, la dignidad y el bienestar y produzca cohesi\u00f3n social y felicidad en las gentes por mejorar la calidad de la muerte, por prevenir, curar o cuidar las enfermedades infecto contagiosas y cr\u00f3nicas degenerativas, que mitigue el dolor y cuide y rehabilite o prevenga la invalidez.<\/p>\n<p>Un Servicio Nacional de Salud para los pobres es un pobre Servicio p\u00fablico de salud. La muerte, la enfermedad, la invalidez y el dolor tienen en su origen y en su desarrollo clase social, por ello la solidaridad debe ser un valor de clase y una caracter\u00edstica del los servicios de salud. Precisamente por eso. Porque somos solidarios.<\/p>\n<p>Un SNS que genere desarrollo y que sea parte de \u00e9l, que redistribuya la renta social de la riqueza producida en el Pa\u00eds y est\u00e9 atento a los problemas. Los sistemas de salud dejan de ser mecanismos de redistribuci\u00f3n de la riqueza, de la renta social, y no generan salud cuando no se planifican y no se regulan democr\u00e1ticamente. Entonces se producen crecimientos incontrolados, inercias profesionales y se generan ganancias para las multinacionales,\u00a0 reproduciendo capital para los\u00a0 sectores lucrativos del sector financiero.<\/p>\n<p>El poder econ\u00f3mico, el poder pol\u00edtico, el poder medi\u00e1tico, el poder profesional y el poder sindical, entre otros, dibujan un mapa necesario de conocer en todos los servicios de salud, por todos los lideres cl\u00ednicos, pol\u00edticos y Comunitarios, precisamente, para intervenir activamente equilibr\u00e1ndolos y dimension\u00e1ndolos adecuadamente, por el bien social y por la salud de nuestros pueblos y por garantizar la eficacia y la eficiencia de las acciones de salud.<\/p>\n<p>Unas nuevas relaciones \u00e9ticas con la industria y con las multinacionales de farmacia. Unas nuevas relaciones \u00e9ticas con los pacientes, horizontales, donde el estigma desaparezca, sobre todo en la enfermedad mental, aunque no \u00fanicamente, y los y las pacientes sean ciudadanos de plenos derechos, donde el consentimiento informado sea un buen y habitual instrumento de trabajo en la democratizaci\u00f3n del conocimiento medico. Un SNS amable donde sus profesionales y trabajadores comprendan el compromiso de servicio con los pacientes.<\/p>\n<p>UN SNS donde la planificaci\u00f3n, la regulaci\u00f3n, el control democr\u00e1tico y el liderazgo otorgue capacidad a los l\u00edderes pol\u00edticos y sociales, y tambi\u00e9n a los lideres profesionales, \u00a0para implementar las reformas necesarias para lograr mas calidad en la gesti\u00f3n de los servicios y las cotas mas altas de salud y bienestar en la regulaci\u00f3n de los objetivos y acciones de los propios servicios de salud.<\/p>\n<p><strong>Sin embargo,<\/strong><\/p>\n<p>Sabemos que m\u00e1s de un 30% de la medicaci\u00f3n de nuestros pacientes es inadecuada, sobre todo en las personas mayores con problemas cr\u00f3nicos. Que entre un 10 y un 30% de los ingresos hospitalarios son inadecuados y que un tercio de las estancias son innecesarias. Asimismo conocemos que un tercio de todos lo estudios de imagen son innecesarios. Y en fin, es conocido que las relaciones habituales de los profesionales sanitarios y los pacientes suelen estar te\u00f1idas con problemas de jerarquizaci\u00f3n, mal trato en ocasiones, y falta de respeto a las propias creencias, en muchas instituciones sanitarias, sobre todo en pa\u00edses donde la buena gobernanza y la lucha contra la corrupci\u00f3n aun tiene un importante recorrido.<\/p>\n<p>En los servicios p\u00fablicos no todo siempre y en todos los lugares funciona bien. Pero hay que defenderlos para mejorarlos. Esta es la paradoja. No podemos ni debemos emprender sistemas paralelos alternativos no sostenibles en el denominado sector \u201cprivado social\u201d, aunque no solo, creando expectativas que no se cumplen en el tiempo. (Bill Gates?)<\/p>\n<p>Son las capacidades instaladas la base de los procesos de reforma, de los cambios en el trato y de cambios en las hegemon\u00edas dentro del sistemas de salud, mas atenci\u00f3n primaria, mas profesionales de enfermer\u00eda y t\u00e9cnicos medios, mas personas y lideres comunitarios formados participando, mas salud publica y mas control y regulaci\u00f3n del sector privado y sobre todo, de sus m\u00e1rgenes de negocio, de su cultura de consumo y su marketing, tantas veces inadecuados,\u00a0 cuando no perversos.<\/p>\n<p>El conocimiento cient\u00edfico, la formaci\u00f3n de pregrado y de post grado y la investigaci\u00f3n cl\u00ednica y social deben estar exentos de conflictos de inter\u00e9s con los patrocinadores, tanto en los servicios como en la propia Universidad.<\/p>\n<p>La salud mental, la salud laboral, la salud escolar, la salud buco dental y la atenci\u00f3n a las drogodependencias y otras adicciones son, todas ellas, partes del Servicio Nacional de Salud. Asi como los servicios sanitarios de la Seguridad Social, las organizaciones para al salud gremiales, o militares\u2026u otros subsistemas de salud. Como el cuerpo humano es la suma de \u00f3rganos y aparatos pero cada persona es algo cualitativamente distinto a la suma de partes. As\u00ed los distintos subsistemas de salud son y deben ser parte del mismo Plan de Salud, de los mismos objetivos, criterios, protocolos y regulaci\u00f3n, que el conjunto del Servicio de Salud, conservando su propia autonom\u00eda pero dando calidad e integridad al conjunto del Sistema de Salud. Es tiempo de integrar de coordinar de buscar la eficiencia y de evitar reinos de taifas sin sentido hist\u00f3rico, que tuvieron su l\u00f3gica en el tiempo.<\/p>\n<p>Nunca como hasta ahora ha habido avances tan importantes en las ciencias sociales, en las ciencias de la salud, en el conocimiento cient\u00edfico. Pero el abismo norte sur tambi\u00e9n ha producido desigualdad en el acceso a dichas tecnolog\u00edas, a dicho conocimiento m\u00e9dico.<\/p>\n<p>La distribuci\u00f3n desigual de los recursos se a\u00f1ade a ese desigual acceso a las tecnolog\u00edas. Es pues una accesibilidad, desigual, limitada, condicionada y en el mejor de los casos, de los llamados \u201cpaquetes b\u00e1sicos\u201d. Tecnolog\u00edas para pocos en pocos lugares y con gastos de divisas de los presupuestos p\u00fablicos que se agotan r\u00e1pidamente por los pagos de la deuda externa.<\/p>\n<p><strong>Un c\u00edrculo infernal.<\/strong><\/p>\n<p>Debemos empezar por cuestionar una distribuci\u00f3n de recursos basados en los modelos de desarrollo centro-periferia. Una concentraci\u00f3n impensable, por inadecuada, de recursos humanos y t\u00e9cnicos materiales\u00a0 en las metr\u00f3polis y,\u2026 los m\u00e9dicos de a\u00f1o social a las \u00e1reas rurales. Otro modelo de desarrollo es posible.<\/p>\n<p>Posiblemente cuando vayamos pasando de la administraci\u00f3n del personal sanitario a una gesti\u00f3n de las personas, habr\u00e1 que establecer otra pol\u00edtica de incentivos que priorice a los profesionales que est\u00e1n donde la gente m\u00e1s les necesita. Posiblemente cuando hablemos de sistemas resolutivos de atenci\u00f3n a los problemas de nuestros pacientes, debamos reflexionar sobre como aumentar la capacidad resolutiva de nuestro primer nivel de atenci\u00f3n, con qu\u00e9 personas y con que tecnolog\u00edas. Posiblemente debamos repensar lo que se denomina \u201chegemon\u00eda biom\u00e9dica\u201d de los sistemas de salud, y organizar los sistemas de conocimiento de otra manera\u00a0 para que la gente que mas nos necesita tenga los mejores profesionales a su disposici\u00f3n.<\/p>\n<p>Me gustar\u00eda que charl\u00e1semos de algunas cosas mas, de b\u00fasqueda de alternativas, aprovecharemos los trabajo en grupos si fuera posible, de c\u00f3mo construir redes sociales entre las organizaciones profesionales y las redes ciudadanas de car\u00e1cter estable. Como utilizar las tecnolog\u00edas de la informaci\u00f3n.<\/p>\n<p>Me gustar\u00eda proponer alguna reflexi\u00f3n sobre la migraci\u00f3n de los profesionales de la salud de los pa\u00edses del sur a los del \u00a0norte y su repercusi\u00f3n econ\u00f3mica y en t\u00e9rminos de salud en las poblaciones, y los problemas de descapitalizacion de la inteligencia y los problemas \u00e9ticos que genera.<\/p>\n<p>Me hubiera gustado dedicar mas tiempo a como las malas condiciones de trabajo, cualquiera que sean estas, generan malestar, enfermedad y muerte, y que hacer ante todo ello cuando establezcamos los mapas de riesgos laborales..<\/p>\n<p>Acaso seria tambi\u00e9n importante debatir acerca de los problemas de la seguridad alimentaria, la alimentaci\u00f3n y la malnutrici\u00f3n, el hambre y las cosechas, el agua, su acceso y su gesti\u00f3n (la principal causa de disminuci\u00f3n de enfermedades infecto contagiosas en el s XIX y XX). La producci\u00f3n de alimentos transgenicos, la utilizaci\u00f3n de agrot\u00f3xicos\u00a0 los m\u00e9todos intensivos de producci\u00f3n de alimentos y sus responsabilidades por su consumo en las epidemias de la Obesidad, la HTA, las nefropat\u00edas, las cardiopat\u00edas, las neumopatias y otros problemas de salud.<\/p>\n<p>Me gustar\u00eda que hici\u00e9semos alguna reflexi\u00f3n sobre los que se denomina prevenci\u00f3n cuaternaria o una utilizaci\u00f3n racional del sistema de salud.<\/p>\n<p>Y en fin, tambi\u00e9n creo m\u00e1s que conveniente hablar sobre la solidaridad, el internacionalismo, la camarader\u00eda y\u00a0 la complicidad entre nosotros que deber\u00edamos impregnar en los sistemas de atenci\u00f3n en donde trabajamos y que cualifica la condici\u00f3n humana.<\/p>\n<blockquote>\n<p>El derecho humano a la salud, en el marco de los determinantes sociales, en este mundo que nos toca vivir tiene algunos problemas. Los conocemos, y este conocimiento refuerza nuestras capacidades de lucha y de resistencia, porque otro mundo, mas saludable,\u00a0 es posible.<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<h3>Y para acabar,<\/h3>\n<p>Hubo una generaci\u00f3n de m\u00e9dicos vascos que nos formamos en nuestros primeros balbuceos en la salud p\u00fablica en Cuba, all\u00e1 en los a\u00f1os 80. Hace ya 33 a\u00f1os. Fue para todos nosotros un honor y un privilegio. Nunca renunciaremos a este patrimonio cient\u00edfico, social, pol\u00edtico y humano, que nos aport\u00f3 la peque\u00f1a isla de Cuba y sus gentes, y por ello estamos hoy aqu\u00ed, gozando de la complicidad de todos ustedes.<\/p>\n<h3 style=\"text-align: center;\"><strong>Gracias. Eskerrik asko<\/strong><\/h3>\n<p>Bilbao, oto\u00f1o del 2013<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center;\"><a href=\"https:\/\/osalde.org\/osalde-en-el-salvador-2\/\">OSALDE EN EL SALVADOR: CONGRESO INTERNACIONAL PARA LA REFORMA SANITARIA (GALERIA)<\/a><\/h3>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<strong>Fuente:\u00a0<\/strong>Charla de Juan Luis Ur\u00eda en El Salvador &#8220;El Derecho Humano a la Salud&#8221;<\/p>\n<p><!--more--><\/p>\n<p><strong>EL DERECHO HUMANO A LA SALUD<\/strong><\/p>\n<blockquote>\n<p>\u201cLa enfermedad es un producto de la vida social\u201d. R. Virchow<\/p>\n<\/blockquote>\n<p>Es dif\u00edcil proponerles temas para la reflexi\u00f3n distintos a los que ya Mario Rovere les comunico a muchos de ustedes el pasado a\u00f1o en\u00a0 Cuenca (Ecuador) sobre el derecho a la salud en la Aldea Global.<\/p>\n<p>Es realmente complicado innovar a algunos de nuestros maestros, a algunos de los \u201cSalubristas\u201d que nuestra Am\u00e9rica ha producido desde los a\u00f1os 60. Pensadores como Gustavo Molina, Hern\u00e1n San Mart\u00edn, Hugo Behm, Mario Testa, \u2026.<\/p>\n<p>No es f\u00e1cil comunicar cosas muy distintas de las que escribieron los lideres de la medicina social, escritores, investigadores, profesionales de la salud, militantes, \u00a0que desde el SXIX lucharon por demostrar el profundo enraizamiento de la salud de los pueblos en las ciencias sociales, mejor dicho, de la salud como condici\u00f3n y resultado de los distintos contextos sociales, econ\u00f3micos y pol\u00edticos.<\/p>\n<p>Fueron H. Sigerist, R. Virchow, F. Engels,\u2026 los que fueron sembrando en tierras fruct\u00edferas sus ideas, al calor de las luchas obreras del primer capitalismo industrial.<\/p>\n<p>Siguieron G. Rosen, M. Terris, Knox,\u2026 y lleg\u00f3 la Comisi\u00f3n de Determinantes Sociales en mayo del 2007 en la 57\u00aa Asamblea Mundial de la Salud. Se invit\u00f3 a M Marmot, G Belinguer, Amartya Sen,\u2026entre otros, y en agosto del 2008 se present\u00f3 el primer informe con tres prioridades, con tres urgencias:<\/p>\n<ol>\n<li>Mejorar las condiciones de vida.<\/li>\n<li>Luchar contra la distribuci\u00f3n desigual del poder y los recursos.<\/li>\n<li>Medir la magnitud del problema, analizar y evaluar los efectos de las intervenciones.<\/li>\n<\/ol>\n<p>Algunos enseguida se preguntaron \u00bfY que opina la sociedad civil? \u00bfHa sido consultada? Otros y otras comentaban que no dec\u00eda nada de la guerra y de la violencia mas o menos estructural como determinante social, algunos, mas atrevidos, discut\u00edan que no pone en cuesti\u00f3n el modelo de desarrollo y no menciona apenas nada del mercado, nada del\u00a0 capitalismo neoliberal, no habla de \u2026<\/p>\n<p>La verdad es que nunca antes que hoy, la salud y el derecho humano al disfrute de la\u00a0 salud y a las cotas mas altas posibles de bienestar social, han sido tan cuestionados.<\/p>\n<p>La hegemon\u00eda del neoliberalismo en el escenario internacional en un hecho.<\/p>\n<p>La crisis, como dice Harvey, es un proceso racionalizador de la irracionalidad del capitalismo. Ni m\u00e1s ni menos. Se trata de recuperar los modelos m\u00e1s especulativos de acumulaci\u00f3n de capital. Las crisis son parte intr\u00ednseca del Sistema.<\/p>\n<p>La cultura de los derechos pol\u00edticos y sociales est\u00e1 en retroceso. El mercado manda.<\/p>\n<p>No hay arbitraje internacional. La OMS tambi\u00e9n est\u00e1 esponsorizada, precisamente para evitar la quiebra econ\u00f3mica de algunos de sus programas y servicios. No le andan a la zaga otras agencias internacionales del sistema de NNUU.<\/p>\n<p>Las transnacionales y sus representantes, siempre acompa\u00f1adas por el FMI, el BM y la OMC, intentan liderar las econom\u00edas, los gobiernos y los pueblos.<\/p>\n<p>Pero si hablamos de hegemon\u00edas y de liderazgos, hay que convenir con A. Gramsci, el gran pensador italiano que, \u00e9stas, no se tejen siempre de igual manera. Que hay que repensar los sistemas de alianzas y que organizar nuevas hegemon\u00edas es posible, tal y como Am\u00e9rica latina est\u00e1 ense\u00f1ando al mundo. Alianzas sustentadas en los intereses de las mayor\u00edas sociales. Alianzas sur-sur (en los \u00faltimos 30 a\u00f1os el comercio internacional entre los pa\u00edses del sur pas\u00f3 del 8% al 27%), alianzas que combinen lo institucional con las redes sociales, alianzas, en fin, incluyendo formas de doble poder, de nuevo tipo que hay que repensar despacio.<\/p>\n<p>Son tiempos de b\u00fasqueda y de resistencia, pero no siempre ha sido as\u00ed, y \u00a0Am\u00e9rica ha sido ejemplo de m\u00faltiples y variados caminos de conquista de derechos sociales y pol\u00edticos a lo largo de su rica historia.<\/p>\n<p>Es una lucha dif\u00edcil pero apasionante por m\u00e1s libertad y democracia, por m\u00e1s paz y menos violencia, por m\u00e1s desarrollo humano, por m\u00e1s cohesi\u00f3n social y de una vida m\u00e1s saludable para nuestras familias, para nuestras comunidades, para nuestros pueblos.<\/p>\n<p><strong>Pero vayamos por partes.<\/strong><\/p>\n<p>El derecho humano a la salud tiene que ver con los servicios de salud, con m\u00e9dicos, con acceso a los medicamentos necesarios y con capacidades tecnol\u00f3gicas diagnosticas y terap\u00e9uticas. Tienen que ver con la interculturalidad y la inclusi\u00f3n, con una nueva \u00e9tica en las relaciones medico\/paciente, con la profundidad de las Reformas emprendida en el sector, tanto en el primer nivel como en el \u00e1mbito hospitalario de la atenci\u00f3n, con las estrategias de promoci\u00f3n de la salud en el \u00e1mbito de la salud comunitaria, aunque no solo. Con la extensi\u00f3n de las coberturas de servicios y programas, con las pol\u00edticas contra la fragmentaci\u00f3n de los servicios de salud, con participaci\u00f3n popular y con la calidad en la gesti\u00f3n de los servicios, la calidad no se programa al margen de los planes de gesti\u00f3n sino que forman parte del sistema de gesti\u00f3n de las organizaciones (Oscar dixit) y en la adecuada gesti\u00f3n de los recursos humanos.<\/p>\n<p>Todo ello, a lo que volveremos mas tarde, \u00a0sin duda tiene que ver con el derecho a la salud, pero empecemos por lo importante.<\/p>\n<p>Como dec\u00eda la declaraci\u00f3n del Movimiento de Salud por los Pueblos (MSP) de octubre de este mismo a\u00f1o reunidos en Cuenca (Ecuador) \u201cnuestra lucha por el derecho a la salud se da en el centro de la crisis de la civilizaci\u00f3n capitalista\u201d.<\/p>\n<p><strong>En nuestra opini\u00f3n, hoy lo importante es<\/strong><\/p>\n<p>La pobreza y al extrema pobreza, o como vivir una vida plena de capacidades y de opciones sin inequidades.<\/p>\n<p>Una vida en la paz, sin guerras y sin violencias<\/p>\n<p>Y un ecosistema sostenible.\u00a0 Un medio ambiente fuente de vida agradable para vivir y no sujeto a agresiones y cat\u00e1strofes que sesgan vidas y quiebran sue\u00f1os y proyectos.<\/p>\n<p>Insistimos que la guerra, la pobreza y el medio en el que vivimos son el gran determinante social de nuestra salud, de nuestro bienestar. Unas breves reflexiones.<\/p>\n<h3><strong>La pobreza<\/strong><\/h3>\n<p>No nos referimos solamente a la ausencia de recursos y de medios de vida, de condiciones b\u00e1sicas de desarrollo ni a crecimientos econ\u00f3micos desarrollistas. Queremos proponer con A. Son la idea de la erradicaci\u00f3n de la extrema pobreza y de la pobreza y proponer un desarrollo humano de las capacidades de las personas, en ambientes de libertad, desarrollo de capacidades e, insistimos, de capacidades con opciones.<\/p>\n<p>Por ello en ocasiones necesitamos sostenibilidad estructural en los repartos de la riqueza y de los recursos. Por ello, en ocasiones, las formas de redistribuci\u00f3n de prestaciones social en forma de extensi\u00f3n de programas y servicios de salud, en forma de escolarizar el 100% de los ni\u00f1os y ni\u00f1as en primaria y en secundaria, y las propuesta de programas de protecci\u00f3n social de nuestra gente mayor y los mas necesitados de la sociedad, son elementos mas importantes que el crecimiento de recursos, que la acumulaci\u00f3n de recursos.<\/p>\n<p>No es hoy entendible que un crecimiento econ\u00f3mico en el desorden social y sin controles democr\u00e1ticos en su reparto sea lo necesario o lo \u00fatil. La erradicaci\u00f3n de la pobreza, y del analfabetismo, debe necesariamente ir acompa\u00f1ada con procesos de empoderamiento civil. Es en la democracia plena donde se dan las condiciones del gozar de m\u00e1s salud, de m\u00e1s libertad, de potenciar las capacidades de las personas.<\/p>\n<p>El crecimiento econ\u00f3mico, en s\u00ed mismo, ha demostrado su fracaso en claves de desarrollo humano, y las pol\u00edticas de ajuste estructural, la gravedad y la injusticia de las pol\u00edticas econ\u00f3micas que no tienen a los hombres y a las mujeres en el centro de su acci\u00f3n pol\u00edtica y social. Como dice el\u00a0 Presidente M\u00fajica, no hay crecimiento sin las personas, si no para qu\u00e9 o para quien es el crecimiento. Y debemos a\u00f1adir, no hay salud sin pol\u00edticas productivas distributivas, sostenibles, humildes, que tengan la redistribuci\u00f3n social como eje d e las pol\u00edticas.<\/p>\n<p>El PNUD afirma, sin embargo, en su \u00faltimo informe 2013 sobre el \u00cdndice de Desarrollo Humano (IDH) que por primera vez en 150 a\u00f1os la producci\u00f3n combinada de las tres econom\u00edas lideres del mundo en desarrollo, China, India y Brasil, es pr\u00e1cticamente igual al PIB combinado de las potencias industriales mas consolidadas del norte, Canad\u00e1, Francia, Alemania, Italia, el Reino Unido y Estados Unidos. Esta situaci\u00f3n significa un reequilibrio impresionante del poder econ\u00f3mico mundial. En 1950, los tres pa\u00edses juntos representaban solo el 10% de la econom\u00eda mundial.<\/p>\n<p>Al parecer la clase media del SUR crece r\u00e1pidamente en tama\u00f1o, ingresos y expectativas.<\/p>\n<p>El \u00faltimo informe de la CEPAL sostiene que el 40% de la poblaci\u00f3n con ingresos m\u00e1s bajos capta en promedio el 15% total del ingreso mientras que el 10% de la poblaci\u00f3n con \u00a0ingresos mas altos posee el 32%. Am\u00e9rica latina por tanto contin\u00faa siendo la Regi\u00f3n m\u00e1s desigual del mundo. Si bien observando los resultados de los \u00faltimos diez a\u00f1os se constatan mejoras distributivas en la mayor\u00eda de los pa\u00edses de la regi\u00f3n, la situaci\u00f3n continua siendo cr\u00edtica. De 17 pa\u00edses considerados por la CEPAL, el \u00edndice de GINI se redujo un 1% anual en nueve casos, entre ellos se encuentra Argentina, Venezuela y Bolivia., los tres con tasas superiores de reducci\u00f3n del 2%.<\/p>\n<p>La desigualdad tiene efectos perversos sobre la salud, pero tambi\u00e9n sobre la democracia y la libertad. El crecimiento general del IDH detectado en el 2013 de muchos pa\u00edses en desarrollo va acompa\u00f1ado, sin embargo, de una creciente desigualdad en los ingresos, patrones insostenibles de consumo, elevado gasto en defensa y escasa cohesi\u00f3n social.<\/p>\n<p>Si bien que la econom\u00eda crezca es una condici\u00f3n necesaria, no implica por si misma la eliminaci\u00f3n de la pobreza. Algunos programas de trasferencias condicionadas con los sectores mas desfavorecidos en Brasil, en Argentina, en Ecuador, y en M\u00e9xico, al parecer, junto con Bolivia y Venezuela,\u00a0 han contribuido en disminuir las desigualdades. Otra forma de econom\u00eda social es posible. El buen Vivir Com\u00fan, es posible.<\/p>\n<h3><strong>La guerra.<\/strong><\/h3>\n<p>Son m\u00e1s d e 30 conflictos de baja, alta o media intensidad, los que en este momento se est\u00e1n desarrollando en nuestro planeta. Solamente la silenciosa guerra en la Republica Democr\u00e1tica del Congo, en los \u00faltimos 6 a\u00f1os, arroja la cifra de m\u00e1s de 5 millones de muertos. \u00bfEn que tasa metemos estos muertos? \u00bfY los desplazados? \u00bfY las violaciones sistem\u00e1ticas de miles de mujeres? \u00bfY los ni\u00f1os soldados? Y \u00bflas epidemias en comunidades desestructuradas?<\/p>\n<p>Parece que las denominadas nuevas democracias \u00e1rabes no se estabilizan. Es dif\u00edcil que as\u00ed sea por el momento. T\u00fanez, Egipto, Libia, Mal\u00ed Y la RASD (la verg\u00fcenza de la descolonizaci\u00f3n espa\u00f1ola en el \u00e1rea) siguen siendo fuentes de conflicto, en claves de violencia. Siria, Irak, Afganist\u00e1n, Palestina, Somalia, Chechenia, Sri Lanka, \u2026<\/p>\n<p>Debemos ser optimistas, el proceso d e negociaci\u00f3n de las FARC\u00a0 con el gobierno Colombiano en La Habana y la distensi\u00f3n nuclear entre Ir\u00e1n y EEUU no son malas noticias. Esperaremos.<\/p>\n<p>Es la cultura de la violencia. Es la fascinaci\u00f3n de los polic\u00edas y los ladrones, la fascinaci\u00f3n testoter\u00f3nica por los ej\u00e9rcitos,<\/p>\n<p>Es la violencia de las desigualdades y de las hegemon\u00edas del complejo militar industrial de EEUU. Y del narcotr\u00e1fico galopante de nuestros pueblos y ciudades. La fascinaci\u00f3n del dinero contra la vida.<\/p>\n<p>Sin duda nos conviene a todos y a todas trabajar con m\u00e1s profusi\u00f3n una cultura de la paz, una cultura alternativa que se haga un hueco en los medios de comunicaci\u00f3n y abogue por otro tipo de relaciones sociales. Otras relaciones de poder.<\/p>\n<h3><strong>Nuestra casa, el cambio clim\u00e1tico.<\/strong><\/h3>\n<p>Es el calentamiento global. \u00bfD\u00f3nde metemos los 10 mil muertos del reciente hurac\u00e1n que asol\u00f3 Filipinas hace apenas unas semanas? Y antes Jap\u00f3n, y Hait\u00ed, y el hurac\u00e1n Mitch, Y el siguiente, y el katrina, en Nueva Orle\u00e1ns. Que est\u00e1 pasando? \u00bfNo vivimos en lugares seguros?<\/p>\n<p>En Nueva York, el 9 de mayo de 1992 se adopt\u00f3 la Convenci\u00f3n marco de las Naciones Unidas sobre el cambio clim\u00e1tico en la que se reconoce que el problema del cambio clim\u00e1tico es real. Parece necesario disminuir la emisi\u00f3n de gases que producen el efecto invernadero (GEI). Ya son 195 naciones las que han ratificado dicha Convenci\u00f3n.<\/p>\n<p>El 11 de diciembre del 1997 se celebra el Protocolo de Kyoto, en Jap\u00f3n, que pone en pr\u00e1ctica los tratados de la Convenci\u00f3n y exige a los 37 pa\u00edses industriales que se reunieron a estabilizar las emisiones de gases de efecto invernadero, por la quema de f\u00f3siles combustibles.<\/p>\n<p>La economista argentina Graciela Chichilnisky propuso una de las tres propuestas que se incluyeron en dicho Protocolo, los \u201cbonos\u00a0 de carbono\u201d, que son un mecanismo internacional de descontaminaci\u00f3n para reducir las emisiones contaminantes al medio ambiente.<\/p>\n<p>Parecer\u00eda urgente organizar nuevos consensos en torno a la reducci\u00f3n de emisiones causantes del calentamiento global, tanto de empresas, como en la producci\u00f3n agr\u00edcola, actividad industrial, energ\u00eda, uso de recursos naturales, entre otras.<\/p>\n<p>La alteraci\u00f3n de los equilibrios de los ecosistemas, locales o regionales est\u00e1n generando enfermedad, muerte, resistencia bacteriana, intoxicaciones, cat\u00e1strofes y exclusiones e inequidades sociales y sanitarias. La agresibidad de las trasnacionales en la deforestaci\u00f3n, y eliminaci\u00f3n de espacios naturales movidos por la mercantilizaci\u00f3n especulativa de los negocios de siempre (extractivos, gasisticos, madereros,\u2026) no para, pero las actividades de los grupos sociales, grupos ind\u00edgenas, grupos a los que se les altera el habitat inmediato y diario, van logrando \u00e9xitos, como en Ecuador, poco a poco.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Construir una salud con dignidad para las personas y para la Madre Tierra.<\/strong><\/p>\n<p>No quiero hablar de los servicios de salud y de los recursos para la salud y su influencia en garantizar el derecho humano a la salud sin hacer una menci\u00f3n especial a la violencia de g\u00e9nero, verdadera epidemia social en nuestros pa\u00edses.<\/p>\n<p>Creemos que las agresiones a las mujeres dentro y fuera del entorno familiar, las violaciones en condiciones de guerra, masivas, y de paz, las desigualdades en salud por motivos de genero, la garant\u00eda de los derechos sexuales y reproductivos, el derecho al aborto, y, en fin el respeto a la libre determinaci\u00f3n de la mujer, sobre su cuerpo y sus decisiones es a\u00fan una asignatura pendiente en nuestros pa\u00edses y debe figurar, en nuestro criterio, en la primera pagina de nuestras agendas.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Dignificar nuestras propuestas.<\/strong><\/p>\n<p>El tr\u00e1fico de mujeres con fines de explotaci\u00f3n econ\u00f3mica y sexual, la discriminaci\u00f3n de homosexuales y lesbianas, los derechos de las trabajadoras sexuales y de las personas transexuales, son problemas en los que tenemos que pensar como salubristas.<\/p>\n<p>Como profesionales de la salud como investigadores y lideres pol\u00edticos y sociales, hemos de pensar sobre del \u201cestado de la cuesti\u00f3n\u201d.<\/p>\n<p>Hablar de tasas escandalosas de embarazos adolescentes, la mayor\u00eda de ellos resultados de violaciones a ni\u00f1as y a adolescentes en el entorno familiar. De ITS o de la propagaci\u00f3n del VIH por violaciones sistematizadas, es reducir el problema a magnitudes, a n\u00fameros, siempre necesarios por otra parte, \u00a0que no pueden expresar el dolor, la verg\u00fcenza y la indignidad para la condici\u00f3n humana que supone este problema.<\/p>\n<p>Es especialmente grave el crecimiento del feminicidio, del asesinato de mujeres en\u00a0 Am\u00e9rica latina.<\/p>\n<p>Este conjunto de problemas de salud, de salud f\u00edsica y mental, no tiene otro origen que el sistema de dominaci\u00f3n de los hombres, de distribuci\u00f3n del poder en el seno de las familias, en el seno de nuestras Comunidades.<\/p>\n<p>Los distintos poderes y los medios de comunicaci\u00f3n ninguneando hasta el infinito el papel de la mujer son, en no poca medida, responsables de trasmitir culturas de opresi\u00f3n y\u00a0 falta de respeto hacia las mujeres en general.<\/p>\n<p>Atendamos las propuestas de las organizaciones feministas, de las l\u00edderes comunitarias, de las profesionales de la salud con conciencia y, en fin de nuestro propio coraz\u00f3n. Son nuestras compa\u00f1eras, hijas, madres y hermanas. Son ciudadanas, sin m\u00e1s.<\/p>\n<p>Dicho lo dicho, vayamos, a dar unas pinceladas acerca de los Servicios de Salud. Sobre los m\u00e9dicos, sobre los medicamentos sobre la Tecnolog\u00eda y sobre como lo estamos haciendo para garantizar el derecho humano a la salud.<\/p>\n<p>Desde la l\u00facida Declaraci\u00f3n del Alma Ata, en el 78, sobre la Atenci\u00f3n Primaria de la Salud y la primera Declaraci\u00f3n para la salud de los pueblos del 2000 en Bangladesh, tenemos claro la propuesta:<\/p>\n<p>Un Servicio Nacional de salud, cuya propiedad y financiamiento sea publico, la organizaci\u00f3n sea de car\u00e1cter integrado y coordinado en todos sus niveles de atenci\u00f3n, tanto en el \u00e1mbito ambulatorio como en el hospitalario; integrado y coordinado con estrategias de promoci\u00f3n y prevenci\u00f3n de la salud y con el \u00e1mbito socio sanitario, atravesado por la calidad en sus prestaciones, con criterios de equidad, esto es evitando desigualdades en sus actividades, programas y servicios, desigualdades de renta, de genero, geogr\u00e1ficas, de edad u otras condiciones f\u00edsicas o ps\u00edquicas, de condici\u00f3n \u00e9tnica o ind\u00edgena, de creencia o de grupo o clase social.<\/p>\n<p>Cuidado con las privatizaciones, algunos pensaron ya desde finales de los 80 que la salud era una gran negocio que no pod\u00edan perder. Debemos blindar los sistemas p\u00fablicos de salud en nuestros pa\u00edses y adaptarlos a lo necesario, siempre buscando las alianzas sociales oportunas para su sostenimiento y defensa.<\/p>\n<p>Un Servicio Nacional de Salud descentralizado, alejado de la fascinaci\u00f3n de la tecnolog\u00eda medica, pero utiliz\u00e1ndola en lo necesario. Con criterios de racionalizacion, producci\u00f3n, solidaridad y necesidad.<\/p>\n<p>Con accesibilidad universal a todos los servicios y a una cartera de actividades consensuada con los agentes sociales, de marcado car\u00e1cter comunitario, donde la participaci\u00f3n social sea un a verdadera escuela de empoderamiento civil en los procesos de gesti\u00f3n de los programas y servicios y tambi\u00e9n en el mismo proceso de vivencia de la enfermedad. Una participaci\u00f3n no instrumentalizada fuera de las relaciones de poder que otorga el conocimiento medico a los profesionales. Una participaci\u00f3n que busque la autogesti\u00f3n y la autonom\u00eda del paciente. Que busque la no dependencia de las personas hacia los sistemas m\u00e9dicos de atenci\u00f3n.<\/p>\n<p>El tama\u00f1o de los Servicios de Salud, la dimensi\u00f3n de las denominadas carteras de servicios o conjunto de actividades que el sistema ofrece a su poblaci\u00f3n, siempre condicionada por \u00a0las necesidades conocidas, siempre tiene que ver con la voluntad pol\u00edtica de los lideres, con las prioridades establecidas que es, al fin y al cabo, \u00a0una forma de voluntad pol\u00edtica y, \u00e9sta, con la permanente negociaci\u00f3n con los agentes sociales y comunitarios, en el marco econ\u00f3mico en el que se d\u00e9 dicha negociaci\u00f3n. Estos son los limites<\/p>\n<p>Un Servicio Nacional de Salud no fragmentado que\u00a0 produzca, que proponga sinergias en el conjunto de modelos de atenci\u00f3n a la salud de las personas y los distintos grupos sociales, gremiales o de clase.<\/p>\n<p>Un Servicio Nacional de Salud donde la pol\u00edtica de medicamentos y su acceso se enfrente con inteligencia a los mercaderes de la salud, que proponga una acceso universal a los medicamentos necesarios, seg\u00fan necesidades, que huya de culturas de consumo unidas al sector privado, y que busque sistemas de f\u00e1rmaco vigilancia y de evaluaci\u00f3n de los medicamentos, democr\u00e1ticos y cient\u00edficos.<\/p>\n<p>Un Sistema Nacional de Salud, en fin, que sea el orgullo del pa\u00eds y de su poblaci\u00f3n y que se base en la solidaridad de los j\u00f3venes con los viejos, de los sanos con los enfermos y de los ricos con los pobres. Un SNS para todos y para todas. Basado en sus decisiones en el m\u00e9todo epidemiol\u00f3gico, en la mejor evidencia cient\u00edfica, en los significados culturales de la poblaci\u00f3n y en sistemas de informaci\u00f3n unificados y desagregados. Para los pobres, para las clases medias y, tambi\u00e9n para los ricos. Que impulse el desarrollo, la dignidad y el bienestar y produzca cohesi\u00f3n social y felicidad en las gentes por mejorar la calidad de la muerte, por prevenir, curar o cuidar las enfermedades infecto contagiosas y cr\u00f3nicas degenerativas, que mitigue el dolor y cuide y rehabilite o prevenga la invalidez.<\/p>\n<p>Un Servicio Nacional de Salud para los pobres es un pobre Servicio p\u00fablico de salud. La muerte, la enfermedad, la invalidez y el dolor tienen en su origen y en su desarrollo clase social, por ello la solidaridad debe ser un valor de clase y una caracter\u00edstica del los servicios de salud. Precisamente por eso. Porque somos solidarios.<\/p>\n<p>Un SNS que genere desarrollo y que sea parte de \u00e9l, que redistribuya la renta social de la riqueza producida en el Pa\u00eds y est\u00e9 atento a los problemas. Los sistemas de salud dejan de ser mecanismos de redistribuci\u00f3n de la riqueza, de la renta social, y no generan salud cuando no se planifican y no se regulan democr\u00e1ticamente. Entonces se producen crecimientos incontrolados, inercias profesionales y se generan ganancias para las multinacionales,\u00a0 reproduciendo capital para los\u00a0 sectores lucrativos del sector financiero.<\/p>\n<p>El poder econ\u00f3mico, el poder pol\u00edtico, el poder medi\u00e1tico, el poder profesional y el poder sindical, entre otros, dibujan un mapa necesario de conocer en todos los servicios de salud, por todos los lideres cl\u00ednicos, pol\u00edticos y Comunitarios, precisamente, para intervenir activamente equilibr\u00e1ndolos y dimension\u00e1ndolos adecuadamente, por el bien social y por la salud de nuestros pueblos y por garantizar la eficacia y la eficiencia de las acciones de salud.<\/p>\n<p>Unas nuevas relaciones \u00e9ticas con la industria y con las multinacionales de farmacia. Unas nuevas relaciones \u00e9ticas con los pacientes, horizontales, donde el estigma desaparezca, sobre todo en la enfermedad mental, aunque no \u00fanicamente, y los y las pacientes sean ciudadanos de plenos derechos, donde el consentimiento informado sea un buen y habitual instrumento de trabajo en la democratizaci\u00f3n del conocimiento medico. Un SNS amable donde sus profesionales y trabajadores comprendan el compromiso de servicio con los pacientes.<\/p>\n<p>UN SNS donde la planificaci\u00f3n, la regulaci\u00f3n, el control democr\u00e1tico y el liderazgo otorgue capacidad a los l\u00edderes pol\u00edticos y sociales, y tambi\u00e9n a los lideres profesionales, \u00a0para implementar las reformas necesarias para lograr mas calidad en la gesti\u00f3n de los servicios y las cotas mas altas de salud y bienestar en la regulaci\u00f3n de los objetivos y acciones de los propios servicios de salud.<\/p>\n<p><strong>Sin embargo,<\/strong><\/p>\n<p>Sabemos que m\u00e1s de un 30% de la medicaci\u00f3n de nuestros pacientes es inadecuada, sobre todo en las personas mayores con problemas cr\u00f3nicos. Que entre un 10 y un 30% de los ingresos hospitalarios son inadecuados y que un tercio de las estancias son innecesarias. Asimismo conocemos que un tercio de todos lo estudios de imagen son innecesarios. Y en fin, es conocido que las relaciones habituales de los profesionales sanitarios y los pacientes suelen estar te\u00f1idas con problemas de jerarquizaci\u00f3n, mal trato en ocasiones, y falta de respeto a las propias creencias, en muchas instituciones sanitarias, sobre todo en pa\u00edses donde la buena gobernanza y la lucha contra la corrupci\u00f3n aun tiene un importante recorrido.<\/p>\n<p>En los servicios p\u00fablicos no todo siempre y en todos los lugares funciona bien. Pero hay que defenderlos para mejorarlos. Esta es la paradoja. No podemos ni debemos emprender sistemas paralelos alternativos no sostenibles en el denominado sector \u201cprivado social\u201d, aunque no solo, creando expectativas que no se cumplen en el tiempo. (Bill Gates?)<\/p>\n<p>Son las capacidades instaladas la base de los procesos de reforma, de los cambios en el trato y de cambios en las hegemon\u00edas dentro del sistemas de salud, mas atenci\u00f3n primaria, mas profesionales de enfermer\u00eda y t\u00e9cnicos medios, mas personas y lideres comunitarios formados participando, mas salud publica y mas control y regulaci\u00f3n del sector privado y sobre todo, de sus m\u00e1rgenes de negocio, de su cultura de consumo y su marketing, tantas veces inadecuados,\u00a0 cuando no perversos.<\/p>\n<p>El conocimiento cient\u00edfico, la formaci\u00f3n de pregrado y de post grado y la investigaci\u00f3n cl\u00ednica y social deben estar exentos de conflictos de inter\u00e9s con los patrocinadores, tanto en los servicios como en la propia Universidad.<\/p>\n<p>La salud mental, la salud laboral, la salud escolar, la salud buco dental y la atenci\u00f3n a las drogodependencias y otras adicciones son, todas ellas, partes del Servicio Nacional de Salud. Asi como los servicios sanitarios de la Seguridad Social, las organizaciones para al salud gremiales, o militares\u2026u otros subsistemas de salud. Como el cuerpo humano es la suma de \u00f3rganos y aparatos pero cada persona es algo cualitativamente distinto a la suma de partes. As\u00ed los distintos subsistemas de salud son y deben ser parte del mismo Plan de Salud, de los mismos objetivos, criterios, protocolos y regulaci\u00f3n, que el conjunto del Servicio de Salud, conservando su propia autonom\u00eda pero dando calidad e integridad al conjunto del Sistema de Salud. Es tiempo de integrar de coordinar de buscar la eficiencia y de evitar reinos de taifas sin sentido hist\u00f3rico, que tuvieron su l\u00f3gica en el tiempo.<\/p>\n<p>Nunca como hasta ahora ha habido avances tan importantes en las ciencias sociales, en las ciencias de la salud, en el conocimiento cient\u00edfico. Pero el abismo norte sur tambi\u00e9n ha producido desigualdad en el acceso a dichas tecnolog\u00edas, a dicho conocimiento m\u00e9dico.<\/p>\n<p>La distribuci\u00f3n desigual de los recursos se a\u00f1ade a ese desigual acceso a las tecnolog\u00edas. Es pues una accesibilidad, desigual, limitada, condicionada y en el mejor de los casos, de los llamados \u201cpaquetes b\u00e1sicos\u201d. Tecnolog\u00edas para pocos en pocos lugares y con gastos de divisas de los presupuestos p\u00fablicos que se agotan r\u00e1pidamente por los pagos de la deuda externa.<\/p>\n<p><strong>Un c\u00edrculo infernal.<\/strong><\/p>\n<p>Debemos empezar por cuestionar una distribuci\u00f3n de recursos basados en los modelos de desarrollo centro-periferia. Una concentraci\u00f3n impensable, por inadecuada, de recursos humanos y t\u00e9cnicos materiales\u00a0 en las metr\u00f3polis y,\u2026 los m\u00e9dicos de a\u00f1o social a las \u00e1reas rurales. Otro modelo de desarrollo es posible.<\/p>\n<p>Posiblemente cuando vayamos pasando de la administraci\u00f3n del personal sanitario a una gesti\u00f3n de las personas, habr\u00e1 que establecer otra pol\u00edtica de incentivos que priorice a los profesionales que est\u00e1n donde la gente m\u00e1s les necesita. Posiblemente cuando hablemos de sistemas resolutivos de atenci\u00f3n a los problemas de nuestros pacientes, debamos reflexionar sobre como aumentar la capacidad resolutiva de nuestro primer nivel de atenci\u00f3n, con qu\u00e9 personas y con que tecnolog\u00edas. Posiblemente debamos repensar lo que se denomina \u201chegemon\u00eda biom\u00e9dica\u201d de los sistemas de salud, y organizar los sistemas de conocimiento de otra manera\u00a0 para que la gente que mas nos necesita tenga los mejores profesionales a su disposici\u00f3n.<\/p>\n<p>Me gustar\u00eda que charl\u00e1semos de algunas cosas mas, de b\u00fasqueda de alternativas, aprovecharemos los trabajo en grupos si fuera posible, de c\u00f3mo construir redes sociales entre las organizaciones profesionales y las redes ciudadanas de car\u00e1cter estable. Como utilizar las tecnolog\u00edas de la informaci\u00f3n.<\/p>\n<p>Me gustar\u00eda proponer alguna reflexi\u00f3n sobre la migraci\u00f3n de los profesionales de la salud de los pa\u00edses del sur a los del \u00a0norte y su repercusi\u00f3n econ\u00f3mica y en t\u00e9rminos de salud en las poblaciones, y los problemas de descapitalizacion de la inteligencia y los problemas \u00e9ticos que genera.<\/p>\n<p>Me hubiera gustado dedicar mas tiempo a como las malas condiciones de trabajo, cualquiera que sean estas, generan malestar, enfermedad y muerte, y que hacer ante todo ello cuando establezcamos los mapas de riesgos laborales..<\/p>\n<p>Acaso seria tambi\u00e9n importante debatir acerca de los problemas de la seguridad alimentaria, la alimentaci\u00f3n y la malnutrici\u00f3n, el hambre y las cosechas, el agua, su acceso y su gesti\u00f3n (la principal causa de disminuci\u00f3n de enfermedades infecto contagiosas en el s XIX y XX). La producci\u00f3n de alimentos transgenicos, la utilizaci\u00f3n de agrot\u00f3xicos\u00a0 los m\u00e9todos intensivos de producci\u00f3n de alimentos y sus responsabilidades por su consumo en las epidemias de la Obesidad, la HTA, las nefropat\u00edas, las cardiopat\u00edas, las neumopatias y otros problemas de salud.<\/p>\n<p>Me gustar\u00eda que hici\u00e9semos alguna reflexi\u00f3n sobre los que se denomina prevenci\u00f3n cuaternaria o una utilizaci\u00f3n racional del sistema de salud.<\/p>\n<p>Y en fin, tambi\u00e9n creo m\u00e1s que conveniente hablar sobre la solidaridad, el internacionalismo, la camarader\u00eda y\u00a0 la complicidad entre nosotros que deber\u00edamos impregnar en los sistemas de atenci\u00f3n en donde trabajamos y que cualifica la condici\u00f3n humana.<\/p>\n<blockquote>\n<p>El derecho humano a la salud, en el marco de los determinantes sociales, en este mundo que nos toca vivir tiene algunos problemas. Los conocemos, y este conocimiento refuerza nuestras capacidades de lucha y de resistencia, porque otro mundo, mas saludable,\u00a0 es posible.<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<h3>Y para acabar,<\/h3>\n<p>Hubo una generaci\u00f3n de m\u00e9dicos vascos que nos formamos en nuestros primeros balbuceos en la salud p\u00fablica en Cuba, all\u00e1 en los a\u00f1os 80. Hace ya 33 a\u00f1os. Fue para todos nosotros un honor y un privilegio. Nunca renunciaremos a este patrimonio cient\u00edfico, social, pol\u00edtico y humano, que nos aport\u00f3 la peque\u00f1a isla de Cuba y sus gentes, y por ello estamos hoy aqu\u00ed, gozando de la complicidad de todos ustedes.<\/p>\n<h3 style=\"text-align: center;\"><strong>Gracias. Eskerrik asko<\/strong><\/h3>\n<p>Bilbao, oto\u00f1o del 2013<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center;\"><a href=\"https:\/\/osalde.org\/osalde-en-el-salvador-2\/\">OSALDE EN EL SALVADOR: CONGRESO INTERNACIONAL PARA LA REFORMA SANITARIA (GALERIA)<\/a><\/h3>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div><span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Maite L\u00f3pez, Beleko noviembre 2018<\/p>\n","protected":false},"author":2,"featured_media":6752,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[849,106,758,820,104,89,759,874],"tags":[108,850],"class_list":["post-6748","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-campana-cooperacion","category-cooperacion","category-documento-osalde","category-enfermeria","category-entrada-del-blog","category-informe","category-memoria","category-salud-comunitaria","tag-beleko","tag-malnutricion"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"eu","enabled_languages":["es","eu"],"languages":{"es":{"title":true,"content":true,"excerpt":false},"eu":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/osalde.org\/eu\/wp-json\/wp\/v2\/posts\/6748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osalde.org\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/osalde.org\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/osalde.org\/eu\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/osalde.org\/eu\/wp-json\/wp\/v2\/comments?post=6748"}],"version-history":[{"count":4,"href":"https:\/\/osalde.org\/eu\/wp-json\/wp\/v2\/posts\/6748\/revisions"}],"predecessor-version":[{"id":13282,"href":"https:\/\/osalde.org\/eu\/wp-json\/wp\/v2\/posts\/6748\/revisions\/13282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/osalde.org\/eu\/wp-json\/wp\/v2\/media\/6752"}],"wp:attachment":[{"href":"https:\/\/osalde.org\/eu\/wp-json\/wp\/v2\/media?parent=6748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/osalde.org\/eu\/wp-json\/wp\/v2\/categories?post=6748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/osalde.org\/eu\/wp-json\/wp\/v2\/tags?post=6748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}